{"id":4197,"date":"2021-01-28T01:46:15","date_gmt":"2021-01-28T01:46:15","guid":{"rendered":"https:\/\/support.mpsoftwarecmms.com\/?page_id=4197"},"modified":"2021-09-24T18:10:04","modified_gmt":"2021-09-24T18:10:04","slug":"existencias-iniciales-costos-iniciales-y-localizacion-de-las-herramientas-al-manejar-multi-almacenes","status":"publish","type":"page","link":"https:\/\/support.mpsoftwarecmms.com\/en_us\/existencias-iniciales-costos-iniciales-y-localizacion-de-las-herramientas-al-manejar-multi-almacenes\/","title":{"rendered":"Stock: initial, initial costs, and location of the tools to handle multi-stores"},"content":{"rendered":"<div id=\"rowone\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"2%\" data-bottom-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section standard_section\"  style=\"padding-top: calc(100vw * 0.02); padding-bottom: calc(100vw * 0.02); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"margin-top: -30px; \" class=\"vc_col-sm-7 wpb_column column_container vc_column_container col neg-marg no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"margin-bottom: 0; padding-bottom: 0;\"><a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/\">Home<\/a> \/ <a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/temario-control-de-herramientas\/\">Control tools<\/a><\/p>\n<h2><strong>Stock: initial, initial costs, and location of the tools to handle multi-stores<\/strong><\/h2>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 60px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col padding-1-percent inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"2px\" data-border-style=\"solid\" data-border-color=\"#999999\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" style=\"border: 2px solid rgba(255,255,255,0); \"><span class=\"border-wrap\" style=\"border-color: #999999;\"><span class=\"border-top\"><\/span><span class=\"border-right\"><\/span><span class=\"border-bottom\"><\/span><span class=\"border-left\"><\/span><\/span><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b141b5\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element  temasrelacionados\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4><strong>Related topics<\/strong><\/h4>\n<p><a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/creacion-de-almacenes-de-herramientas\/#almacenes1\">\u25b8 Introduction to warehouse of tools (multi-stores)<\/a><br \/>\n<a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/creacion-de-almacenes-de-herramientas\/#almacenes2\">\u25b8 Add stores tools (multi-stores)<\/a><br \/>\n<a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/creacion-de-almacenes-de-herramientas\/#almacenes3\">\u25b8 Determination of tools that handles each store<\/a><br \/>\n<a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/analisis-de-almacenes-y-disponibilidad-de-las-herramientas\/#analisisalm1\">\u25b8 Check availability of the tools in each store<\/a><br \/>\n<a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/analisis-de-almacenes-y-disponibilidad-de-las-herramientas\/#analisisalm2\">\u25b8 Query of the total value of the store<\/a><br \/>\n<a href=\"https:\/\/support.mpsoftwarecmms.com\/en_us\/analisis-de-almacenes-y-disponibilidad-de-las-herramientas\/#analisisalm3\">\u25b8 Comparative warehouse<\/a><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"norutinariosb\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b14626\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"right\"><div style=\"margin-top: 30px; width: 80px; height: 3px; margin-bottom: 30px;\" data-width=\"80\" data-animate=\"\" data-animation-delay=\"\" data-color=\"accent-color\" class=\"divider-small-border\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 enlacesindice wpb_column column_container vc_column_container col child_column padding-1-percent inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"left-right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4>Las existencias y costos iniciales de una herramienta son variables en cada almac\u00e9n al igual que su localizaci\u00f3n.<\/h4>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 30px; width: 80px; height: 3px; margin-bottom: 30px;\" data-width=\"80\" data-animate=\"\" data-animation-delay=\"\" data-color=\"accent-color\" class=\"divider-small-border\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>El registro de existencias y costos iniciales es el proceso con el cual el usuario indica la situaci\u00f3n inicial de su inventario para poder comenzar a trabajar y generar movimientos de entrada y de salida, movimientos de resguardos y devoluciones, para poder realizar consultas con los valores actualizados.<\/p>\n<\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>La versatilidad del sistema de control de herramientas de la suite MP versi\u00f3n 10 le permite registrar sus existencias iniciales al momento de crear herramientas y almacenes, o bien, posteriormente permite editar de forma individual o masiva las existencias iniciales, costo inicial y localizaci\u00f3n de las herramientas en los diferentes almacenes.<\/p>\n<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_wrapper\">\n<p>Tambi\u00e9n para facilidad y agilidad en la implementaci\u00f3n del sistema de control de herramientas, el usuario puede comenzar a trabajar con las herramientas a los cuales les ha capturado sus valores iniciales, evitando as\u00ed, tener que capturar los valores iniciales de todos las herramientas para comenzar a utilizar el sistema. Es importante se\u00f1alar que una vez que se ha realizado un movimiento con una herramienta, no se podr\u00e1n realizar modificaciones de los registros iniciales (existencia inicial y costo inicial) de esa herramienta en el almac\u00e9n en que se realiz\u00f3 el movimiento.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>The log of initial stock can be done from the module <strong>Tools<\/strong> and from the module <strong>Stores<\/strong>.<\/p>\n<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>Desde el m\u00f3dulo de Herramientas pueden registrar las existencias iniciales de las herramientas en cada uno de los almacenes; en cambio, en el m\u00f3dulo de Almacenes, se registra la existencia inicial de las herramientas que se contienen en el almac\u00e9n seleccionado.<\/p>\n<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\"><\/div>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>Para capturar los valores iniciales de sus herramientas desde el m\u00f3dulo de <strong>Tools<\/strong> and select in the submenu <strong>Stores and initial stock.<\/strong><\/p>\n<\/div>\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b14de4\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"\" alt=\"\"  \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/selecciona-varias-modulo-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/submenu-almacenes-existencias-iniciales-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b15c8e\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"\" alt=\"\"  \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/selecciona-varias-modulo-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-initial-stock-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b16896\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/01\/almacenes-existencias-iniciales-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b16dc7\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-initial-stock-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>To capture the stock from the module <strong>Stores<\/strong> ingrese a dicho m\u00f3dulo, seleccione un almac\u00e9n en caso de contar con multi-almacenes y luego seleccione el o las herramientas que desea editar, posteriormente seleccione la acci\u00f3n <strong>Herramientas y existencias iniciales<\/strong> located in the submenu of the module.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b173f0\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"\" alt=\"\"  \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/almacenes-herramientas-en-almacen-seleccionado-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b17f8f\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"100\" width=\"100\" data-animation=\"fade-in\" src=\"\" alt=\"\"  \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/warehouses-tools-in-warehouse-selected-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b18b7c\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-herramientas-existencias-iniciales-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b193ca\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-tools-initial-stock-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>En ambos casos se habilitar\u00e1 la edici\u00f3n m\u00faltiple en la malla para registrar la informaci\u00f3n. Esta malla permite seleccionar las herramientas que se tienen en el almac\u00e9n marcando la casilla de selecci\u00f3n, modificar la existencia inicial y modificar el costo inicial de las herramientas seleccionadas. Es importante se\u00f1alar que no es posible modificar los valores iniciales de las herramientas a las cuales se les ha generado un movimiento y por lo tanto se encontrar\u00e1 marcado el s\u00edmbolo de movimientos.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b19d08\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/existencias-iniciales-almacen-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b19fc9\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"50%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/initial-stock-warehouse-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><strong>Note:<\/strong> La herramienta solo se bloquea en el almac\u00e9n desde donde se genero el movimiento de salida o entrada.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 60px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"norutinariosb\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><strong>Location in store<br \/>\n<\/strong><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>El sistema de control de herramientas permite documentar el lugar en que se encuentra f\u00edsicamente la herramienta dentro del almacen (Ej. pasillo, anaquel o nivel), facilitando con esto su ubicaci\u00f3n al momento de hacer el resguardo.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Al igual que las existencias y costos iniciales, la localizaci\u00f3n de los repuestos en los almacenes se puede editar desde el m\u00f3dulo de Repuestos y consumibles, as\u00ed como desde el m\u00f3dulo de Almacenes.<\/p>\n<p>Para indicar la localizaci\u00f3n de los repuestos, selecciona los repuestos de la malla y luego selecciona la acci\u00f3n Localizaciones dentro del submen\u00fa.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b1acb5\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/selecciona-herramientas-modulo-almacenes-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/submenu-almacenes-localizacion-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b1b69b\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/select-tools-module-warehouses-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-draw=\"\" data-border-thickness=\"2px\" data-padding=\"20px\" data-color=\"extra-color-2\" style=\"\" >\r\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 50px; line-height: 50px; height: 50px; width: 50px;\" class=\"fa fa-arrow-circle-right\"><\/i><\/div>\r\n\t<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/submenu-warehouses-location-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>En ambos casos se abrir\u00e1 una malla modificable con el campo de localizaci\u00f3n para capturar la localizaci\u00f3n de las herramientas en el o los almacenes. Esta localizaci\u00f3n puede ser modificada en cualquier momento.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a97d33b1c024\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseesp\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-almacenes-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Editing window locations view from the module stores<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/02\/localizacion-herramientas-modulo-herramientas-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Ventana de edici\u00f3n de localizaciones vista desde el m\u00f3dulo de herramientas<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a97d33b1c80e\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section  claseing\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-warehouses-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Editing window locations view from the module stores<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-border-radius=\"none\" data-shadow=\"none\" data-animation=\"fade-in\" >\r\n      <div class=\"inner\">\r\n        <div class=\"hover-wrap\" data-hover-animation=\"none\"> \r\n          <div class=\"hover-wrap-inner\">\r\n            <a href=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools.png\" class=\"pp\">\r\n              <img class=\"img-with-animation skip-lazy gris\" data-delay=\"0\" height=\"1140\" width=\"1600\" data-animation=\"fade-in\" src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools.png\" alt=\"\" srcset=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools.png 1600w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools-300x214.png 300w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools-1024x730.png 1024w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools-768x547.png 768w, https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2021\/07\/location-tools-module-tools-1536x1094.png 1536w\" sizes=\"(min-width: 1450px) 75vw, (min-width: 1000px) 85vw, 100vw\" \/>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n      <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p>Ventana de edici\u00f3n de localizaciones vista desde el m\u00f3dulo de herramientas<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d33b1d12a\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"5%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  vc_row-o-equal-height vc_row-flex  vc_row-o-content-middle standard_section linksbottom\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"true\"><div class=\"inner-wrap\"><div class=\"row-bg using-bg-color\"  style=\"background-color: #08131c; \"><\/div><\/div><div class=\"row-bg-overlay\" style=\"background-color:#08131c;  opacity: 0.95; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b1d227\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column centered-text padding-2-percent inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"left-right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h1>Can&#039;t find the answer to your doubts or questions?<\/h1>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d33b1d4f2\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section standard_section claseesp\"  style=\"padding-top: calc(100vw * 0.02); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg using-bg-color\"  style=\"background-color: #f2f2f2; \"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b1d5fb\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; -webkit-transform:  translateY(-100px); transform:  translateY(-100px);\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent inherit_tablet inherit_phone\" data-cfc=\"true\" data-using-bg=\"true\" data-t-w-inherits=\"default\" data-shadow=\"medium_depth\" data-border-radius=\"15px\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#008cee\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #008cee;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3><strong>Please contact our technical support team<\/strong><\/h3>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 15px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4 style=\"text-align: left;\">We offer FREE technical support via:<\/h4>\n<p style=\"text-align: left; font-weight: 500;\">\u2705 Video conferencing<br \/>\n\u2705 Phone call<br \/>\n\u2705 E-mail<br \/>\n\u2705 Whatsapp<br \/>\n\u2705 Chat<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<a class=\"nectar-button large see-through-2\"  style=\"margin-top: 30px; margin-bottom: 1px; border-color: #ffffff; color: #ffffff;\" target=\"_blank\" href=\"https:\/\/mpsoftware.com.mx\/opciones-de-soporte-tecnico\/\" data-color-override=\"#ffffff\"  data-hover-color-override=\"#ffffff\" data-hover-text-color-override=\"#000000\"><span>Contact FREE technical support<\/span><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent inherit_tablet inherit_phone\" data-cfc=\"true\" data-using-bg=\"true\" data-t-w-inherits=\"default\" data-shadow=\"medium_depth\" data-border-radius=\"10px\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ffbb00\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ffbb00;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3><strong>Frequently asked questions<br \/>\n<\/strong><\/h3>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 15px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: left; font-weight: 500;\">Please check our site frequently asked questions to learn more about the schemes of subscription, our wide range of connectivity options, solution of technical problems, etc..<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 15px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large see-through-2\"  style=\"margin-top: 30px; margin-bottom: 1px; border-color: #ffffff; color: #ffffff;\" target=\"_blank\" href=\"https:\/\/desk.zoho.com\/portal\/mpsoftwaremexico\/es\/kb\" data-color-override=\"#ffffff\"  data-hover-color-override=\"#ffffff\" data-hover-text-color-override=\"#000000\"><span>Go to frequently asked Questions<\/span><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d33b1db8e\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"2%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section standard_section claseing\"  style=\"padding-top: calc(100vw * 0.02); padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg using-bg-color\"  style=\"background-color: #f2f2f2; \"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b1dc98\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_row-o-equal-height vc_row-flex standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; -webkit-transform:  translateY(-100px); transform:  translateY(-100px);\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent inherit_tablet inherit_phone\" data-cfc=\"true\" data-using-bg=\"true\" data-t-w-inherits=\"default\" data-shadow=\"medium_depth\" data-border-radius=\"15px\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#008cee\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #008cee;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3><strong>Please contact our technical support team<\/strong><\/h3>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 15px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h4 style=\"text-align: left;\">We offer FREE technical support via:<\/h4>\n<p style=\"text-align: left; font-weight: 500;\">\u2705 Video conferencing<br \/>\n\u2705 Phone call<br \/>\n\u2705 E-mail<br \/>\n\u2705 Whatsapp<br \/>\n\u2705 Chat<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<a class=\"nectar-button large see-through-2\"  style=\"margin-top: 30px; margin-bottom: 1px; border-color: #ffffff; color: #ffffff;\" target=\"_blank\" href=\"https:\/\/mpsoftware.com.mx\/opciones-de-soporte-tecnico\/\" data-color-override=\"#ffffff\"  data-hover-color-override=\"#ffffff\" data-hover-text-color-override=\"#000000\"><span>Contact FREE technical support<\/span><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\" color: #ffffff;\" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column centered-text padding-6-percent inherit_tablet inherit_phone\" data-cfc=\"true\" data-using-bg=\"true\" data-t-w-inherits=\"default\" data-shadow=\"medium_depth\" data-border-radius=\"10px\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#474747\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #474747;\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h3><strong>Additionally, we offer training courses<br \/>\n<\/strong><\/h3>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 15px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p style=\"text-align: left; font-weight: 500;\">Our flexible options of online training and face-to-face will provide you with all the knowledge necessary to understand and implement your software maintenance MP.<\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large see-through-2\"  style=\"\" target=\"_blank\" href=\"https:\/\/mpsoftware.com.mx\/cotiza-en-linea-tu-mp-version-10\/\" data-color-override=\"false\"  data-hover-color-override=\"#ffffff\" data-hover-text-color-override=\"#000000\"><span>Trading training packages<\/span><\/a>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d33b1e1dd\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"3%\" data-bottom-percent=\"3%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section standard_section claseesp\"  style=\"padding-top: calc(100vw * 0.03); padding-bottom: calc(100vw * 0.03); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"row-bg using-bg-color\"  style=\"background-color: #474747; \"><\/div><\/div><div class=\"row-bg-overlay\" ><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a97d33b1e2d8\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row standard_section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<h2><strong>Additionally, we offer training courses<\/strong><\/h2>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><span lang=\"es\">Our flexible options of online training and face-to-face will provide you with all the knowledge necessary to understand and implement your software maintenance MP.<\/span><\/p>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column centered-text no-extra-padding inherit_tablet inherit_phone\"   data-t-w-inherits=\"default\" data-bg-cover=\"\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-hover-bg=\"\" data-hover-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\">\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-bg-overlay-wrap\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\"><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button large see-through-2\"  style=\"\" target=\"_blank\" href=\"https:\/\/mpsoftware.com.mx\/cotiza-en-linea-tu-mp-version-10\/\" data-color-override=\"false\"  data-hover-color-override=\"#ffffff\" data-hover-text-color-override=\"#000000\"><span>Trading training packages<\/span><\/a>\r\n<div class=\"wpb_text_column wpb_content_element\" >\r\n\t<div class=\"wpb_wrapper\">\r\n\t\t<p><br \/>\n<div id=\"myModA\" class=\"modal\"> \r\n    <!-- Modal content -->\r\n    <div class=\"modal-content\"> <span class=\"close\" onclick=\"modalCloseA();\">\u00d7<\/span> <br>\r\n        <!------->\r\n        <h4><strong>Consideration if you are going to use the engine for Firebird database<\/strong><\/h4>\r\n\t\t\t  <br><br>\r\n        <p>However, the excellent performance that this database engine provides, it is important to take into account that this database engine is only recommended for users that do NOT want to use the mobile applications MPsolicitudes or MPmobile, because these APPs ARE NOT COMPATIBLE WITH THE ENGINE FIREBIRD DATABASES.<\/p>\r\n        <!-------> \r\n    <\/div>\r\n<\/div><br \/>\n<div id=\"myModB\" class=\"modal\"> \r\n    <!-- Modal content -->\r\n    <div class=\"modal-contentb\"> <span class=\"close\" onclick=\"modalCloseB();\">\u00d7<\/span> <br>\r\n        <!------->\r\n        <h4><strong>Name of the database and its location.<\/strong><\/h4>\r\n\t\t\t  <br><br>\r\n        <p>Regarding the name of the database: The name that you define can&#039;t wear white space, and the number of characters allowed maximum is 25, for example Maintenance Plant 1 instead use Hyphens or underscores this: Mantenimiento_Planta_1, in addition to it is not allowed that the name of your database-carry special characters such as these: \u00a1 &#034; # , $ % &amp; ( \u00bf ) ? } { The reason for this is that there are some rules or policies that the database engines prohibit the use of these characters.<\/p>\r\n\t\t\t\t\t\r\n\t\t\t<p>You&#039;ll have another field of up to 50 characters that will allow a broader description and complete database.<\/p>\r\n\t\t\t<p>Example:<\/p>\r\n\t\t\t<table style=\"width: 100%;\">\r\n<tbody>\r\n<tr>\r\n<td width=\"30%\"><strong>Name of the database<\/strong><\/td>\r\n<td width=\"30%\"><strong>Name of the access to the database<\/strong><\/td>\r\n<td width=\"40%\"><strong>Long description of the database<\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">PLANTA_SPEREN_1<\/td>\r\n<td width=\"30%\">ACCESS TO PLANTA_SPEREN_1<\/td>\r\n<td width=\"40%\">PLANT SPEREN PARQUE INDUSTRIAL EXPORTEC II<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">PLANTA_SPEREN_2<\/td>\r\n<td width=\"30%\">ACCESS TO PLANTA_SPEREN_2<\/td>\r\n<td width=\"40%\">PLANT SPEREN PARQUE INDUSTRIAL HUEHUETOCA<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">PLANTA_SPEREN_3<\/td>\r\n<td width=\"30%\">ACCESS TO PLANTA_SPEREN_3<\/td>\r\n<td width=\"40%\">PLANT SPEREN INDUSTRIAL PARK JILOTEPEC<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">HOTEL_Mara_A<\/td>\r\n<td width=\"30%\">ACCESS TO HOTEL_Mara_A<\/td>\r\n<td width=\"40%\">Hotel All Inclusive Mara Place, Cancun, QR<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">HOTEL_Mara_B<\/td>\r\n<td width=\"30%\">ACCESS TO HOTEL_Mara_B<\/td>\r\n<td width=\"40%\">Gran Executive Hotel Mara Place mexico City, Mexico<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">HOSPITAL_TRAUMATOLOGIA<\/td>\r\n<td width=\"30%\">ACCESS TO HOSPITAL_TRAUMATOLOGIA<\/td>\r\n<td width=\"40%\">Hospital of Traumatology Loma Verdes, Naucalpan<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">HOSPITAL_NEUROLOGIA<\/td>\r\n<td width=\"30%\">ACCESS TO HOSPITAL_NEUROLOGIA<\/td>\r\n<td width=\"40%\">National institute of Neurology and Neurosurgery, CDMX<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">FLOTILLA_1<\/td>\r\n<td width=\"30%\">ACCESS TO FLOTILLA_1<\/td>\r\n<td width=\"40%\">Fleet Cars and trucks SPEREN EXPORTEC II<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n\t\t\t<p>After you&#039;ve created your databases in the MP, these are hosted on the Database Server that you&#039;ve chosen. For example, the databases created by the streamlined staying in your computer, the path in which you can find is C:\\Windows\\SysWow64 or C:\\Windows\\System32. Regularly are Files with the Extension.FDB<\/p>\r\n\t\t\t<p>The databases created in the following types of databases: MariaDB, MySQL, SQL-Server, MPcloud and Oracle does not generate Files. The information is stored in multiple tables of schema information, or in special environments of your server.<\/p>\r\n\t\t\t<p>Regardless of the type of database Server that you manage, we recommend to make backups of your information frequently so that you get a receipt of your information as a preventive measure in case of an emergency, see the section Backup and restore a database.<\/p>\r\n        <!-------> \r\n    <\/div>\r\n<\/div><br \/>\n<div id=\"myModC\" class=\"modal\"> \r\n    <!-- Modal content -->\r\n    <div class=\"modal-contentb\"> <span class=\"close\" onclick=\"modalCloseC();\">\u00d7<\/span> <br>\r\n        <!------->\r\n\t\t<h3><strong>Server IP, user name and password of the database engine<\/strong><\/h3>\r\n\t\t<br><br>\r\n\r\n<p>Today, virtually all companies have at least one IT professional who is responsible for, among many other functions to manage the data and servers of the company. Among their functions include the administration of a database engine, which, for security reasons, has access by means of a user name and a password. If not, any person could enter the network, and provide high-databases, query, modify and even delete confidential information of the company.<\/p>\r\n\r\n<p>For example:<\/p>\r\n<table style=\"width:100%;\">\r\n<tr>\r\n<td width=\"30%\"><strong>DATABASE ENGINE<\/strong><\/td>\r\n<td width=\"40%\"><strong>ADMINISTRATOR USER BY DEFAULT<\/strong><\/td>\r\n<td width=\"30%\"><strong>PASSWORD\r\n<\/strong><strong>(Known only to the manager of IT)<\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">MySQL<\/td>\r\n<td width=\"40%\">root<\/td>\r\n<td width=\"30%\">******<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">Microsoft SQL-Server<\/td>\r\n<td width=\"40%\">sa<\/td>\r\n<td width=\"30%\">******<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">Oracle<\/td>\r\n<td width=\"40%\">System<\/td>\r\n<td width=\"30%\">******<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">MariaDB<\/td>\r\n<td width=\"40%\">root<\/td>\r\n<td width=\"30%\">******<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"30%\">Firebird<\/td>\r\n<td width=\"40%\">SYSDBA<\/td>\r\n<td width=\"30%\">******<\/td>\r\n<\/tr>\r\n<\/table>\r\n<p>When you create a database, or a new connection on the MP, the program prompts you for the server name or IP where you will create or is the database to which you want to connect to, as well as a user name and password.<\/p>\r\n<h4><em>The username and password that here we ask, are precisely those that allow access to the <\/em><em>database engine <\/em><em>permissions privileges to create the database. <\/em><\/h4>\r\n<br><br>\r\n\t\t\t<img src=\"https:\/\/support.mpsoftwarecmms.com\/wp-content\/uploads\/2020\/07\/ingresa-informacion-del-servidor.png\" style=\"width:50%; heigth:auto;\">\r\n<br><br>\r\n<p>Now, the administrator of the database can also create different user accounts to allow access to more people by giving them privileges and permissions custom.<\/p>\r\n\r\n<h4><em>With the aim of not to use the administrator user of IT and its respective password each time that the department of maintenance required to create a database or a connection to an existing database, it is recommended that the IT administrator create a user account specifically for the maintenance department.<\/em><\/h4>\r\n<p>A single user account to the database engine is sufficient for the creation and connection of multiple databases.<\/p>\r\n\r\n<p>The username and password that here is requested, you do not have any relationship with the licenses of use are acquired or the amount of users that can access the database, so that a single user account can be enough, because in this case it refers specifically to the user and password of the database engine.<\/p>\r\n\t\t<!-------> \r\n    <\/div>\r\n<\/div><br \/>\n<div id=\"myModD\" class=\"modal\"> \r\n    <!-- Modal content -->\r\n    <div class=\"modal-contentb\"> <span class=\"close\" onclick=\"modalCloseD();\">\u00d7<\/span> <br>\r\n        <!------->\r\n\t\t<h3><strong>What is a access to the database?<\/strong><\/h3>\r\n\t\t<br><br>\r\n\r\n<p>When you create a database, it automatically creates an access to the database. Access is a file that contains encoded all information regarding the IP address or name of the server where the database resides. This information is also recorded in a QR code, which will facilitate the connection of mobile devices to the database.<\/p>\r\n\t\t<!-------> \r\n    <\/div>\r\n<\/div>\n\t<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Inicio \/ Control de herramientas Existencias iniciales, costos iniciales y localizaci\u00f3n de las herramientas al...","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/pages\/4197"}],"collection":[{"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/comments?post=4197"}],"version-history":[{"count":12,"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/pages\/4197\/revisions"}],"predecessor-version":[{"id":6796,"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/pages\/4197\/revisions\/6796"}],"wp:attachment":[{"href":"https:\/\/support.mpsoftwarecmms.com\/en_us\/wp-json\/wp\/v2\/media?parent=4197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}